{"id":22268,"date":"2016-07-12T02:26:40","date_gmt":"2016-07-12T00:26:40","guid":{"rendered":"http:\/\/www.multimediaweb.eu\/web-agency\/fedora-25-in-arrivo-il-nuovo-fedora-media-writer\/"},"modified":"2016-07-12T02:26:41","modified_gmt":"2016-07-12T00:26:41","slug":"fedora-25-in-arrivo-il-nuovo-fedora-media-writer","status":"publish","type":"post","link":"https:\/\/www.multimediaweb.eu\/web-agency\/fedora-25-in-arrivo-il-nuovo-fedora-media-writer\/","title":{"rendered":"Fedora 25: in arrivo il nuovo Fedora Media Writer"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div readability=\"37.349206349206\">\n<article readability=\"17.896848137536\">\n<p>Il nuovo Fedora Media Writer avr\u00e0 una migliore interfaccia grafica e sar\u00e0 <strong>scritto in C++<\/strong>. Attualmente nel panorama delle distribuzioni sistema del pinguino il modo migliore per creare un media di installazione, tramite un file ISO, \u00e8 usare il tool da shell <em>dd<\/em>. Ma per chi \u00e8 nuovo del mondo sistema del pinguino non si tratta di sicuro della procedura pi\u00f9 semplice rendendo necessario il ricorso a delle guide online.<\/p>\n<p>Per scansare ci\u00f2 sono nati diversi tool, sviluppati dai team delle distribuzioni, che non fanno altro che sfruttare <em>dd<\/em> tramite una Graphics User Interface GUI (<em>Graphical User Interface<\/em>) pi\u00f9 user friendly. Il Fedora Media Writer dovrebbe essere uno dei pi\u00f9 completi una volta finiti i lavori di sviluppo di Fedora 25, infatti guardando alcuni design mockups pubblicati su GitHub \u00e8 possibile vedere come il tool riconosca le diverse flavor di Fedora e anche  altre distribuzioni come <strong>Ubuntu<\/strong>.<\/p>\n<p>Si potr\u00e0 anche dividere i file ISO in 32 o 64bit. Il processo di creazione verr\u00e0 mostrato in modo completo e sar\u00e0 anche possibile scaricare i file ISO direttamente dal tool.<\/p>\n<p>Via <a href=\"https:\/\/fedoraproject.org\/wiki\/Changes\/FedoraMediaWriterAsPrimaryDownloadable\" target=\"_blank\">Fedora<\/a><\/p>\n<p>&#13;<br \/>\n          <!--div class=\"sharelink\">\n              \n\n<ul>\n                  \n\n<li class=\"facebook\"><a href=\"#\" onclick=\"window.open( 'https:\/\/www.facebook.com\/sharer\/sharer.php?u='+encodeURIComponent('http:\/\/blog.html.it\/11\/07\/2016\/fedora-25-in-arrivo-il-nuovo-fedora-media-writer\/'),'condividi l'articolo su facebook', 'width=626,height=436,location=no,directories=no,titlebar=no,toolbar=no,location=no,status=no,menubar=no,scrollbars=no,resizable=no'); return false;\">Facebook<\/a><\/li>\n\n\n                  \n\n<li class=\"twitter\"><a href=\"#\" onclick=\"window.open( 'https:\/\/twitter.com\/share?url=http%3A%2F%2Fblog.html.it%2F11%2F07%2F2016%2Ffedora-25-in-arrivo-il-nuovo-fedora-media-writer%2F&via=html_it&text=Fedora%2025%3A%20in%20arrivo%20il%20nuovo%20Fedora%20Media%20Writer','condividi l'articolo su twitter', 'width=626,height=436,location=no,directories=no,titlebar=no,toolbar=no,location=no,status=no,menubar=no,scrollbars=no,resizable=no'); return false;\">Twitter<\/a><\/li>\n\n\n              <\/ul>\n\n\n          <\/div-->&#13;<br \/>\n          &#13;<br \/>\n\t\t<\/article>\n<div readability=\"5.3181818181818\">\n            <!--\n\n<style>\n\n.newletter-item, .newsletter-box \n  \/*float: left;\n  margin: 5px 0 20px 0;*\/\n  display: block;\n  width: 100%;\n\n\n.newletter-item, .newsletter-box p \n    font-size: 18px;\n    letter-spacing: 0.3px;\n    line-height: 28px;\n    padding: 0 0 34px 0;\n    color: #161616;\n    font-family: 'Alegreya', serif;\n\n\n.newletter-item, .newsletter-box p span \n  font-weight: bold;\n\n\n.newsletter-box img\n    width: 48px;\n    height: auto;\n    margin: 0 auto 34px auto;\n\n\n.newsletter-panel \n  display: block;\n  width: auto;\n  height: 129px;\n  background: url(http:\/\/www.html.it\/wp-content\/themes\/www.html.it\/images\/newsletter\/newsletter-bg.png) no-repeat;\n  position: relative;\n  left: 0px;\n\n.newsletter-panel form \n  margin: 0;\n\n.newsletter-panel .line-item \n  display: block;\n  float: left;\n  margin: 0 0 0 20px;\n  display: block;\n  width: 408px;\n\n.newsletter-panel input \n  float: left;\n  display: block;\n\n.newsletter-panel input[type=\"text\"] \n  margin: 20px 0 10px 20px;\n  width: 395px;\n  height: 26px;\n  line-height: 26px;\n  padding: 2px;\n\n.newsletter-panel input[type=\"radio\"] \n  margin: 6px 3px 0 0;\n\n.newsletter-panel label.radio-item \n  float: left;\n  display: block;\n  font-size: 1em;\n  width: 10px;\n  margin: 6px 10px 0 0;\n\n.newsletter-panel .lable-text \n  display: block;\n  float: left;\n  width: 240px;\n  font-size: 10px !important;\n  color: #333333 !important;\n  line-height: 130%;\n  margin: 6px 0 0 0px !important;\n\n.newsletter-panel .lable-text a \n  color: #333\n\n.newsletter-panel input[type=\"button\"] \n  position: relative;\n  top: -50px;\n  left: 64px;\n  width: 127px;\n  height: 47px;\n  background: url(http:\/\/www.html.it\/wp-content\/themes\/www.html.it\/images\/newsletter\/newsletter-butt.png) no-repeat;\n  background-repeat: no-repeat;\n  border: 0;\n  cursor: pointer;\n\n.newsletter-panel input[type=\"button\"]:hover \n  background-image: url(http:\/\/www.html.it\/wp-content\/themes\/www.html.it\/images\/newsletter\/newsletter-butt-roll.png);\n\n.newsletter-panel label.radio-item \n  font-size: 10px !important;\n\n.error-newsletter\npadding: 10px 20px;\n\n<\/style>\n\n--><\/p>\n<div id=\"newsletter_div\" class=\"newletter-item nav-txt newsletter-box\" readability=\"6.5454545454545\">\n<p>Se vuoi aggiornamenti su <b>Fedora 25: in arrivo il nuovo Fedora Media Writer<\/b> inserisci la tua e-mail nel box qui sotto:<\/p>\n<\/div><\/div><\/div>\n<p><br \/>\n<br \/><a href=\"http:\/\/feedproxy.google.com\/~r\/htmlitedit\/~3\/9cuGoj-FZ3M\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il nuovo Fedora Media Writer avr\u00e0 una migliore interfaccia grafica e sar\u00e0 scritto in C++. Attualmente nel panorama delle distribuzioni sistema del pinguino il modo migliore per creare un media di installazione, tramite un file ISO, \u00e8 usare il tool da shell dd. Ma per chi \u00e8 nuovo del mondo sistema del pinguino non si&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_s2mail":""},"categories":[37],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.13 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fedora 25: in arrivo il nuovo Fedora Media Writer - Web Agency Italia Web Designer realizzazione siti web Italy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.multimediaweb.eu\/web-agency\/fedora-25-in-arrivo-il-nuovo-fedora-media-writer\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fedora 25: in arrivo il nuovo Fedora Media Writer - Web Agency Italia Web Designer realizzazione siti web Italy\" \/>\n<meta property=\"og:description\" content=\"Il nuovo Fedora Media Writer avr\u00e0 una migliore interfaccia grafica e sar\u00e0 scritto in C++. Attualmente nel panorama delle distribuzioni sistema del pinguino il modo migliore per creare un media di installazione, tramite un file ISO, \u00e8 usare il tool da shell dd. Ma per chi \u00e8 nuovo del mondo sistema del pinguino non si...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.multimediaweb.eu\/web-agency\/fedora-25-in-arrivo-il-nuovo-fedora-media-writer\/\" \/>\n<meta property=\"og:site_name\" content=\"Web Agency Italia Web Designer realizzazione siti web Italy\" \/>\n<meta property=\"article:published_time\" content=\"2016-07-12T00:26:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-07-12T00:26:41+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.multimediaweb.eu\/web-agency\/fedora-25-in-arrivo-il-nuovo-fedora-media-writer\/\",\"url\":\"https:\/\/www.multimediaweb.eu\/web-agency\/fedora-25-in-arrivo-il-nuovo-fedora-media-writer\/\",\"name\":\"Fedora 25: in arrivo il nuovo Fedora Media Writer - Web Agency Italia Web Designer realizzazione siti web Italy\",\"isPartOf\":{\"@id\":\"https:\/\/www.multimediaweb.eu\/web-agency\/#website\"},\"datePublished\":\"2016-07-12T00:26:40+00:00\",\"dateModified\":\"2016-07-12T00:26:41+00:00\",\"author\":{\"@id\":\"https:\/\/www.multimediaweb.eu\/web-agency\/#\/schema\/person\/c0748e23499fac2fd73b79d1379fdf42\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.multimediaweb.eu\/web-agency\/fedora-25-in-arrivo-il-nuovo-fedora-media-writer\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.multimediaweb.eu\/web-agency\/fedora-25-in-arrivo-il-nuovo-fedora-media-writer\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.multimediaweb.eu\/web-agency\/fedora-25-in-arrivo-il-nuovo-fedora-media-writer\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.multimediaweb.eu\/web-agency\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fedora 25: in arrivo il nuovo Fedora Media Writer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.multimediaweb.eu\/web-agency\/#website\",\"url\":\"https:\/\/www.multimediaweb.eu\/web-agency\/\",\"name\":\"Web Agency Italia Web Designer realizzazione siti web Italy\",\"description\":\"Web design creazione siti web Italia\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.multimediaweb.eu\/web-agency\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.multimediaweb.eu\/web-agency\/#\/schema\/person\/c0748e23499fac2fd73b79d1379fdf42\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.multimediaweb.eu\/web-agency\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/991cd68bbfd6f946517378a63fc3a1f7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/991cd68bbfd6f946517378a63fc3a1f7?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\/\/www.multimediaweb.eu\/web-agency\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fedora 25: in arrivo il nuovo Fedora Media Writer - Web Agency Italia Web Designer realizzazione siti web Italy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.multimediaweb.eu\/web-agency\/fedora-25-in-arrivo-il-nuovo-fedora-media-writer\/","og_locale":"it_IT","og_type":"article","og_title":"Fedora 25: in arrivo il nuovo Fedora Media Writer - Web Agency Italia Web Designer realizzazione siti web Italy","og_description":"Il nuovo Fedora Media Writer avr\u00e0 una migliore interfaccia grafica e sar\u00e0 scritto in C++. Attualmente nel panorama delle distribuzioni sistema del pinguino il modo migliore per creare un media di installazione, tramite un file ISO, \u00e8 usare il tool da shell dd. Ma per chi \u00e8 nuovo del mondo sistema del pinguino non si...","og_url":"https:\/\/www.multimediaweb.eu\/web-agency\/fedora-25-in-arrivo-il-nuovo-fedora-media-writer\/","og_site_name":"Web Agency Italia Web Designer realizzazione siti web Italy","article_published_time":"2016-07-12T00:26:40+00:00","article_modified_time":"2016-07-12T00:26:41+00:00","author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"admin","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.multimediaweb.eu\/web-agency\/fedora-25-in-arrivo-il-nuovo-fedora-media-writer\/","url":"https:\/\/www.multimediaweb.eu\/web-agency\/fedora-25-in-arrivo-il-nuovo-fedora-media-writer\/","name":"Fedora 25: in arrivo il nuovo Fedora Media Writer - Web Agency Italia Web Designer realizzazione siti web Italy","isPartOf":{"@id":"https:\/\/www.multimediaweb.eu\/web-agency\/#website"},"datePublished":"2016-07-12T00:26:40+00:00","dateModified":"2016-07-12T00:26:41+00:00","author":{"@id":"https:\/\/www.multimediaweb.eu\/web-agency\/#\/schema\/person\/c0748e23499fac2fd73b79d1379fdf42"},"breadcrumb":{"@id":"https:\/\/www.multimediaweb.eu\/web-agency\/fedora-25-in-arrivo-il-nuovo-fedora-media-writer\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.multimediaweb.eu\/web-agency\/fedora-25-in-arrivo-il-nuovo-fedora-media-writer\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.multimediaweb.eu\/web-agency\/fedora-25-in-arrivo-il-nuovo-fedora-media-writer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.multimediaweb.eu\/web-agency\/"},{"@type":"ListItem","position":2,"name":"Fedora 25: in arrivo il nuovo Fedora Media Writer"}]},{"@type":"WebSite","@id":"https:\/\/www.multimediaweb.eu\/web-agency\/#website","url":"https:\/\/www.multimediaweb.eu\/web-agency\/","name":"Web Agency Italia Web Designer realizzazione siti web Italy","description":"Web design creazione siti web Italia","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.multimediaweb.eu\/web-agency\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.multimediaweb.eu\/web-agency\/#\/schema\/person\/c0748e23499fac2fd73b79d1379fdf42","name":"admin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.multimediaweb.eu\/web-agency\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/991cd68bbfd6f946517378a63fc3a1f7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/991cd68bbfd6f946517378a63fc3a1f7?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/www.multimediaweb.eu\/web-agency\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.multimediaweb.eu\/web-agency\/wp-json\/wp\/v2\/posts\/22268"}],"collection":[{"href":"https:\/\/www.multimediaweb.eu\/web-agency\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.multimediaweb.eu\/web-agency\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.multimediaweb.eu\/web-agency\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.multimediaweb.eu\/web-agency\/wp-json\/wp\/v2\/comments?post=22268"}],"version-history":[{"count":1,"href":"https:\/\/www.multimediaweb.eu\/web-agency\/wp-json\/wp\/v2\/posts\/22268\/revisions"}],"predecessor-version":[{"id":22269,"href":"https:\/\/www.multimediaweb.eu\/web-agency\/wp-json\/wp\/v2\/posts\/22268\/revisions\/22269"}],"wp:attachment":[{"href":"https:\/\/www.multimediaweb.eu\/web-agency\/wp-json\/wp\/v2\/media?parent=22268"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.multimediaweb.eu\/web-agency\/wp-json\/wp\/v2\/categories?post=22268"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.multimediaweb.eu\/web-agency\/wp-json\/wp\/v2\/tags?post=22268"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}