{"id":22288,"date":"2016-07-22T04:11:07","date_gmt":"2016-07-22T02:11:07","guid":{"rendered":"http:\/\/www.multimediaweb.eu\/web-agency\/gnome-archive-extraction-nativo-in-nautilus\/"},"modified":"2016-07-22T04:11:07","modified_gmt":"2016-07-22T02:11:07","slug":"gnome-archive-extraction-nativo-in-nautilus","status":"publish","type":"post","link":"https:\/\/www.multimediaweb.eu\/web-agency\/gnome-archive-extraction-nativo-in-nautilus\/","title":{"rendered":"GNOME: Archive Extraction nativo in Nautilus"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div readability=\"37.082997582595\">\n<article readability=\"17.79587628866\">\n<p>Il developer di GNOME Razvan Mihai Chitu \u00e8 all&#8217;opera per integrare le funzionalit\u00e0 di File Roller direttamente nel codice di Nautilus, in modo da ottimizzare ancora di pi\u00f9 le prestazioni e da trasformare questa componente in una feature nativa del file manager di GNOME.<\/p>\n<p>Si tratta di un progetto ideato per il <em>Google Summer of Code 2016<\/em>. Lo sviluppatore ha intenzione di integrare il tutto in Nautilis in modo da semplificare la gestione degli archivi compressi, rendendo possibile la navigazione all&#8217;interno di essi direttamente da Nautilus e dunque senza doversi interfacciare con programmi esterni.<\/p>\n<p>Lo sviluppatore vuole poi utilizzare la libreria <em>gnome-autoar<\/em> per gestire la compressione e la decompressione dei file. Dunque dalla prossima modello stabile del desktop environment dello &#8220;gnomo&#8221;, ovvero GNOME 3.22, molto probabilmente arriveranno nuove patch per Nautilus che andranno ad inglobare il codice dell&#8217;<em>archive extraction<\/em> al suo interno.<\/p>\n<p>Via <a href=\"http:\/\/www.omgubuntu.co.uk\/2016\/07\/native-nautilus-file-extract-archive\" target=\"_blank\">OMG!Ubuntu!<\/a><\/p>\n<p>&#13;<br \/>\n          <!--div class=\"sharelink\">\n              \n\n<ul>\n                  \n\n<li class=\"facebook\"><a href=\"#\" onclick=\"window.open( 'https:\/\/www.facebook.com\/sharer\/sharer.php?u='+encodeURIComponent('http:\/\/blog.html.it\/21\/07\/2016\/gnome-in-arrivo-un-archive-extraction-nativo-per-nautilus\/'),'condividi l'articolo su facebook', 'width=626,height=436,location=no,directories=no,titlebar=no,toolbar=no,location=no,status=no,menubar=no,scrollbars=no,resizable=no'); return false;\">Facebook<\/a><\/li>\n\n\n                  \n\n<li class=\"twitter\"><a href=\"#\" onclick=\"window.open( 'https:\/\/twitter.com\/share?url=http%3A%2F%2Fblog.html.it%2F21%2F07%2F2016%2Fgnome-in-arrivo-un-archive-extraction-nativo-per-nautilus%2F&via=html_it&text=GNOME%3A%20Archive%20Extraction%20nativo%20in%20Nautilus','condividi l'articolo su twitter', 'width=626,height=436,location=no,directories=no,titlebar=no,toolbar=no,location=no,status=no,menubar=no,scrollbars=no,resizable=no'); return false;\">Twitter<\/a><\/li>\n\n\n              <\/ul>\n\n\n          <\/div-->&#13;<br \/>\n          &#13;<br \/>\n\t\t<\/article>\n<div readability=\"5.2962962962963\">\n            <!--\n\n<style>\n\n.newletter-item, .newsletter-box \n  \/*float: left;\n  margin: 5px 0 20px 0;*\/\n  display: block;\n  width: 100%;\n\n\n.newletter-item, .newsletter-box p \n    font-size: 18px;\n    letter-spacing: 0.3px;\n    line-height: 28px;\n    padding: 0 0 34px 0;\n    color: #161616;\n    font-family: 'Alegreya', serif;\n\n\n.newletter-item, .newsletter-box p span \n  font-weight: bold;\n\n\n.newsletter-box img\n    width: 48px;\n    height: auto;\n    margin: 0 auto 34px auto;\n\n\n.newsletter-panel \n  display: block;\n  width: auto;\n  height: 129px;\n  background: url(http:\/\/www.html.it\/wp-content\/themes\/www.html.it\/images\/newsletter\/newsletter-bg.png) no-repeat;\n  position: relative;\n  left: 0px;\n\n.newsletter-panel form \n  margin: 0;\n\n.newsletter-panel .line-item \n  display: block;\n  float: left;\n  margin: 0 0 0 20px;\n  display: block;\n  width: 408px;\n\n.newsletter-panel input \n  float: left;\n  display: block;\n\n.newsletter-panel input[type=\"text\"] \n  margin: 20px 0 10px 20px;\n  width: 395px;\n  height: 26px;\n  line-height: 26px;\n  padding: 2px;\n\n.newsletter-panel input[type=\"radio\"] \n  margin: 6px 3px 0 0;\n\n.newsletter-panel label.radio-item \n  float: left;\n  display: block;\n  font-size: 1em;\n  width: 10px;\n  margin: 6px 10px 0 0;\n\n.newsletter-panel .lable-text \n  display: block;\n  float: left;\n  width: 240px;\n  font-size: 10px !important;\n  color: #333333 !important;\n  line-height: 130%;\n  margin: 6px 0 0 0px !important;\n\n.newsletter-panel .lable-text a \n  color: #333\n\n.newsletter-panel input[type=\"button\"] \n  position: relative;\n  top: -50px;\n  left: 64px;\n  width: 127px;\n  height: 47px;\n  background: url(http:\/\/www.html.it\/wp-content\/themes\/www.html.it\/images\/newsletter\/newsletter-butt.png) no-repeat;\n  background-repeat: no-repeat;\n  border: 0;\n  cursor: pointer;\n\n.newsletter-panel input[type=\"button\"]:hover \n  background-image: url(http:\/\/www.html.it\/wp-content\/themes\/www.html.it\/images\/newsletter\/newsletter-butt-roll.png);\n\n.newsletter-panel label.radio-item \n  font-size: 10px !important;\n\n.error-newsletter\npadding: 10px 20px;\n\n<\/style>\n\n--><\/p>\n<div id=\"newsletter_div\" class=\"newletter-item nav-txt newsletter-box\" readability=\"6.5185185185185\">\n<p>Se vuoi aggiornamenti su <b>GNOME: Archive Extraction nativo in Nautilus<\/b> inserisci la tua e-mail nel box qui sotto:<\/p>\n<\/div><\/div><\/div>\n<p><br \/>\n<br \/><a href=\"http:\/\/feedproxy.google.com\/~r\/htmlitedit\/~3\/ClrJ-ksgpPE\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il developer di GNOME Razvan Mihai Chitu \u00e8 all&#8217;opera per integrare le funzionalit\u00e0 di File Roller direttamente nel codice di Nautilus, in modo da ottimizzare ancora di pi\u00f9 le prestazioni e da trasformare questa componente in una feature nativa del file manager di GNOME. Si tratta di un progetto ideato per il Google Summer of&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_s2mail":""},"categories":[37],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.13 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>GNOME: Archive Extraction nativo in Nautilus - Web Agency Italia Web Designer realizzazione siti web Italy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.multimediaweb.eu\/web-agency\/gnome-archive-extraction-nativo-in-nautilus\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GNOME: Archive Extraction nativo in Nautilus - Web Agency Italia Web Designer realizzazione siti web Italy\" \/>\n<meta property=\"og:description\" content=\"Il developer di GNOME Razvan Mihai Chitu \u00e8 all&#8217;opera per integrare le funzionalit\u00e0 di File Roller direttamente nel codice di Nautilus, in modo da ottimizzare ancora di pi\u00f9 le prestazioni e da trasformare questa componente in una feature nativa del file manager di GNOME. Si tratta di un progetto ideato per il Google Summer of...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.multimediaweb.eu\/web-agency\/gnome-archive-extraction-nativo-in-nautilus\/\" \/>\n<meta property=\"og:site_name\" content=\"Web Agency Italia Web Designer realizzazione siti web Italy\" \/>\n<meta property=\"article:published_time\" content=\"2016-07-22T02:11:07+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.multimediaweb.eu\/web-agency\/gnome-archive-extraction-nativo-in-nautilus\/\",\"url\":\"https:\/\/www.multimediaweb.eu\/web-agency\/gnome-archive-extraction-nativo-in-nautilus\/\",\"name\":\"GNOME: Archive Extraction nativo in Nautilus - Web Agency Italia Web Designer realizzazione siti web Italy\",\"isPartOf\":{\"@id\":\"https:\/\/www.multimediaweb.eu\/web-agency\/#website\"},\"datePublished\":\"2016-07-22T02:11:07+00:00\",\"dateModified\":\"2016-07-22T02:11:07+00:00\",\"author\":{\"@id\":\"https:\/\/www.multimediaweb.eu\/web-agency\/#\/schema\/person\/c0748e23499fac2fd73b79d1379fdf42\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.multimediaweb.eu\/web-agency\/gnome-archive-extraction-nativo-in-nautilus\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.multimediaweb.eu\/web-agency\/gnome-archive-extraction-nativo-in-nautilus\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.multimediaweb.eu\/web-agency\/gnome-archive-extraction-nativo-in-nautilus\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.multimediaweb.eu\/web-agency\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"GNOME: Archive Extraction nativo in Nautilus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.multimediaweb.eu\/web-agency\/#website\",\"url\":\"https:\/\/www.multimediaweb.eu\/web-agency\/\",\"name\":\"Web Agency Italia Web Designer realizzazione siti web Italy\",\"description\":\"Web design creazione siti web Italia\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.multimediaweb.eu\/web-agency\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.multimediaweb.eu\/web-agency\/#\/schema\/person\/c0748e23499fac2fd73b79d1379fdf42\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.multimediaweb.eu\/web-agency\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/991cd68bbfd6f946517378a63fc3a1f7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/991cd68bbfd6f946517378a63fc3a1f7?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\/\/www.multimediaweb.eu\/web-agency\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"GNOME: Archive Extraction nativo in Nautilus - Web Agency Italia Web Designer realizzazione siti web Italy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.multimediaweb.eu\/web-agency\/gnome-archive-extraction-nativo-in-nautilus\/","og_locale":"it_IT","og_type":"article","og_title":"GNOME: Archive Extraction nativo in Nautilus - Web Agency Italia Web Designer realizzazione siti web Italy","og_description":"Il developer di GNOME Razvan Mihai Chitu \u00e8 all&#8217;opera per integrare le funzionalit\u00e0 di File Roller direttamente nel codice di Nautilus, in modo da ottimizzare ancora di pi\u00f9 le prestazioni e da trasformare questa componente in una feature nativa del file manager di GNOME. Si tratta di un progetto ideato per il Google Summer of...","og_url":"https:\/\/www.multimediaweb.eu\/web-agency\/gnome-archive-extraction-nativo-in-nautilus\/","og_site_name":"Web Agency Italia Web Designer realizzazione siti web Italy","article_published_time":"2016-07-22T02:11:07+00:00","author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"admin","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.multimediaweb.eu\/web-agency\/gnome-archive-extraction-nativo-in-nautilus\/","url":"https:\/\/www.multimediaweb.eu\/web-agency\/gnome-archive-extraction-nativo-in-nautilus\/","name":"GNOME: Archive Extraction nativo in Nautilus - Web Agency Italia Web Designer realizzazione siti web Italy","isPartOf":{"@id":"https:\/\/www.multimediaweb.eu\/web-agency\/#website"},"datePublished":"2016-07-22T02:11:07+00:00","dateModified":"2016-07-22T02:11:07+00:00","author":{"@id":"https:\/\/www.multimediaweb.eu\/web-agency\/#\/schema\/person\/c0748e23499fac2fd73b79d1379fdf42"},"breadcrumb":{"@id":"https:\/\/www.multimediaweb.eu\/web-agency\/gnome-archive-extraction-nativo-in-nautilus\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.multimediaweb.eu\/web-agency\/gnome-archive-extraction-nativo-in-nautilus\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.multimediaweb.eu\/web-agency\/gnome-archive-extraction-nativo-in-nautilus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.multimediaweb.eu\/web-agency\/"},{"@type":"ListItem","position":2,"name":"GNOME: Archive Extraction nativo in Nautilus"}]},{"@type":"WebSite","@id":"https:\/\/www.multimediaweb.eu\/web-agency\/#website","url":"https:\/\/www.multimediaweb.eu\/web-agency\/","name":"Web Agency Italia Web Designer realizzazione siti web Italy","description":"Web design creazione siti web Italia","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.multimediaweb.eu\/web-agency\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.multimediaweb.eu\/web-agency\/#\/schema\/person\/c0748e23499fac2fd73b79d1379fdf42","name":"admin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.multimediaweb.eu\/web-agency\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/991cd68bbfd6f946517378a63fc3a1f7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/991cd68bbfd6f946517378a63fc3a1f7?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/www.multimediaweb.eu\/web-agency\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.multimediaweb.eu\/web-agency\/wp-json\/wp\/v2\/posts\/22288"}],"collection":[{"href":"https:\/\/www.multimediaweb.eu\/web-agency\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.multimediaweb.eu\/web-agency\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.multimediaweb.eu\/web-agency\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.multimediaweb.eu\/web-agency\/wp-json\/wp\/v2\/comments?post=22288"}],"version-history":[{"count":1,"href":"https:\/\/www.multimediaweb.eu\/web-agency\/wp-json\/wp\/v2\/posts\/22288\/revisions"}],"predecessor-version":[{"id":22289,"href":"https:\/\/www.multimediaweb.eu\/web-agency\/wp-json\/wp\/v2\/posts\/22288\/revisions\/22289"}],"wp:attachment":[{"href":"https:\/\/www.multimediaweb.eu\/web-agency\/wp-json\/wp\/v2\/media?parent=22288"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.multimediaweb.eu\/web-agency\/wp-json\/wp\/v2\/categories?post=22288"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.multimediaweb.eu\/web-agency\/wp-json\/wp\/v2\/tags?post=22288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}